{"id":1862,"date":"2007-09-25T20:03:35","date_gmt":"2007-09-25T20:03:35","guid":{"rendered":"http:\/\/cipamericas.org\/?p=1862"},"modified":"2009-10-06T14:27:41","modified_gmt":"2009-10-06T14:27:41","slug":"4578","status":"publish","type":"post","link":"https:\/\/www.americas.org\/es\/4578\/","title":{"rendered":"Personal y Voluntarios"},"content":{"rendered":"<table width=\"100%\" cellpadding=\"1\" cellspacing=\"1\" border=\"0\">\n<tr>\n<td colspan=\"2\" valign=\"bottom\">\n<h2>Personal<\/h2>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/879.jpg\" height=\"90\" width=\"115\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Tom Barry, Analista Senior y Fellow del Programa de las Am&eacute;ricas:<\/b> Como analista senior, Tom Barry participa en asignar, escribir y redactar art&iacute;culos importantes y tambi&eacute;n definir objetivos estrat&eacute;gicos del Programa de las Am&eacute;ricas. Empez&oacute; su carrera como activista pol&iacute;tica y analista en Georgetown University en los 1960s. Trabaj&oacute; como<br \/>\n  periodista por el Navajo Times de Nuevo Mexico y en 1971 fund&oacute; su propio peri&oacute;dico. En 1979 co-fund&oacute; el Interhemispheric Resource Center (IRC), y se uni&oacute; con el Center for   International Policy en 2007. Ha escrito o co-escrito m&aacute;s que viente libros sobre M&eacute;xico, Am&eacute;rica Central, el Caribe, ayuda alimenticia, los Naciones Unidas, comercio libre y la pol&iacute;tica exterior de los Estados Unidos. Incluyen: <i>The Great Divide: Challenge of U.S.-Mexico Relations in the 1990s<\/i> (Grove Press), <i>Feeding the Crisis: U.S. Food Aid and Farm Policy in Central America<\/i> (University of Nebraska), <i>The Next Fifty Years: The United Nations and the United States<\/i>, y <i>Zapata&#8217;s Revenge: Free Trade and the Farm Crisis in Mexico<\/i> (South End Press). Tambi&eacute;n ha editado volumenes sobre la pol&iacute;tica exterior como <i>Global Focus: U.S. Foreign policy at the Turn of the Millennium<\/i> (St. Martin&#8217;s Press). <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/809.jpg\" width=\"101\" height=\"148\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Laura Carlsen, Directora del Programa de las Am&eacute;ricas:<\/b> Laura Carlsen hizo la carrera en Pensamiento Social y Instituciones en Stanford University y una maestr&iacute;a en Estudios Latinoamericanos tambi&eacute;n de Stanford. En 1986 recibi&oacute; una beca Fulbright<br \/>\n  para estudiar el impacto de la crisis econ&oacute;mica mexicana en mujeres y ha vivido en la Ciudad de M&eacute;xico desde ese entonces. Ella ha publicado numerosos art&iacute;culos sobre aspectos sociales,<br \/>\n  econ&oacute;micos y politicos de M&eacute;xico, recientemente redactando <i>Confronting Globalization: Economic integration and popular resistance in Mexico<\/i>, y co-escribiendo <i>El Caf&eacute; en Mexico, centroamerica y el caribe: Una salida sustentable a la crisis<\/i>. Antes de unirse con el Programa de las Am&eacute;ricas, fue corresponsal de la revista Latin Trade, editora de Business Mexico, y escritora y investigadora freelance. Como directora del programa, escribe, asigna y redacta materials, representa la organizaci&oacute;n en foros p&uacute;blicos, busca y mantiene relaciones de colaboraci&oacute;n y administra la oficina en la Ciudad de M&eacute;xico. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><b>Photo Not Available<\/b><\/td>\n<td>\n<p><b>Monica Wooters, Assistente del Programa de las Am&eacute;ricas:<\/b> Monica vive en la Ciudad de M&eacute;xico donde trabaja para el Programa de las Am&eacute;ricas del Center for International Policy. Tiene una licenciatura en Antropolog&iacute;a de la University fo Southern California y cuenta con experiencia extensiva en movimientos sociales y derechos humanos en M&eacute;xico y Centroam&eacute;rica. Vivi&oacute; por dos a&ntilde;os en Guatemala y ha participado en estudios de campo en Antropolog&iacute;a Cultural en Guatemala, as&iacute; como en Panam&aacute;. Monica trabaj&oacute; casi dos a&ntilde;os en el tema de derechos humanos y movimientos sociales en Chiapas y Guerrero con el Servicio Internacional para la Paz y la CASA de Paz. Ha conducido delegaciones internacionales para visibilizar a la situaci&oacute;n pol&iacute;tica del sur de M&eacute;xico, monitoreado la pol&iacute;tica de los EEUU hac&iacute;a M&eacute;xico con &eacute;nfasis en la ampliaci&oacute;n de la militarizaci&oacute;n y la criminalizaci&oacute;n de la protesta social y hecho investigaci&oacute;n sobre los impactos de las estrategias del ej&eacute;rcito estadounidense en la pol&iacute;tica estatal de Chiapas y los efectos de las corporaciones trasnacionales en la econom&iacute;a local. Monica es de Los Angeles, California y es biling&uuml;e en ingl&eacute;s y espa&ntilde;ol.<\/i><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><b>Photo Not Available<\/b><\/td>\n<td>\n<p><b>Michael Collins, Assistente de Investigaci&oacute;n:<\/b> Michael Collins vive en la Ciudad de M&eacute;xico donde trabaja como assistente de investigaci&oacute;n para el Programa de las Americas del Centro para Pol&iacute;tica Internacional. Tiene una licenciatura en Ciencias Sociales y Arte de la Universidad Strathclyde en Glasgow. Naci&oacute; en Escocia. Ha vivido en Londres, Par&iacute;s, Catalunya y Madrid y habla Franc&eacute;s, Espa&ntilde;ol y Catal&aacute;n adem&aacute;s de su lengua materna, el Ingl&eacute;s. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><b>Photo Not Available<\/b><\/td>\n<td>\n<p><b>Chellee Chase-Saiz, Nuestra Encargada de P&aacute;ginas Internet:<\/b> Chellee Chase-Saiz es nuestra Encargada de P&aacute;ginas Internet. Tiene m&aacute;s que 10 a&ntilde;os de experiencia en producci&oacute;n a base de medios electr&oacute;nicos y sistemas de informaci&oacute;n. Chellee tambi&eacute;n es maestra y da pl&aacute;ticas de animaci&oacute;n, fue due&ntilde;a de su<br \/>\n  pr&oacute;pia empresa y activista. Como escritora profesional tiene m&aacute;s que 50 art&iacute;culos publicados. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<p>&nbsp;<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"bottom\">\n<h2>Gracias a nuestros voluntarios generosos!<\/h2>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><b>Photo Not Available<\/b><\/td>\n<td>\n<p><b>David Alford<\/b> es un traductor con mucha experiencia tambi&eacute;n en redacci&oacute;n para la p&aacute;gina internet la la Comisi&oacute;n Europea en Bruselas. La apasiona apoyar a causas progresistas en general. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><b>Photo Not Available<\/b><\/td>\n<td>\n<p><b>Adriana Alvarez Andrade<\/b> estudi&oacute; Biolog&iacute;a en la Universidad Veracruzana en Xalapa, en donde particip&oacute; en el movimiento ambientalista y antinuclear de mediados de los 1980s. Es profesora-investigadora de El Colegio de la Frontera Norte, en Tijuana, en donde tambi&eacute;n coordina la Maestr&iacute;a en Administraci&oacute;n Integral del Ambiente. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/896.jpg\" width=\"76\" height=\"96\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Patricia Black<\/b> se gradu&oacute; de la Universidad de California-Davis con una carrera en Espa&ntilde;ol, vivi&oacute; y ense&ntilde;&oacute; en Colombia por tres a&ntilde;os, trabaj&oacute; con los Trabajadores Agr&iacute;colas Unidos un a&ntilde;o, se jubil&oacute; de la Administraci&oacute;n de la Seguridad Social despu&eacute;s de 23 a&ntilde;os y actualmente ense&ntilde;a Espa&ntilde;ol en la Preparatoria Del Norte de Crescent City, CA. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/894.jpg\" width=\"71\" height=\"88\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Mar&iacute;a Dolores Bol&iacute;var<\/b> es licenciada en Ciencia Pol&iacute;tica por la Universidad Estatal de San Diego (SDSU) y doctora en Estudios Culturales y Literarios por la Universidad de California, San Diego (UCSD). Es actualmente periodista independiente, consultora de traducci&oacute;n y catedr&aacute;tica de espa&ntilde;ol en San Diego Mesa College. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/1378.jpg\" width=\"80\" height=\"99\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Eliot Brockner<\/b> es un analista freelance y escritor cubriendo la pol&iacute;tica en Am&eacute;rica Latina y relaciones entre la regi&oacute;n y los Estados Unidos. Su trabajo ha sido publicado en <i>International Relations and Security Network<\/i> y <i>UpsideDownWorld<\/i>. Tambi&eacute;n contribuye a la p&aacute;gina LatAmThought.org. Tiene licenciatura en psicolog&iacute;a y espa&ntilde;ol de Amhurst College y actualmente vive en Nueva York. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><b>Photo Not Available<\/b><\/td>\n<td>\n<p><b>Vicente Casta&ntilde;ar Flores<\/b> es maestro de ingl&eacute;s y traductor profesional independiente. Esta disponible para otros trabajos cuando no esta viajando en bici o buscando maneras creativas de reciclar. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/1102.jpg\" width=\"72\" height=\"84\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Mar&iacute;a de la Soledad Laura Cervantes Ram&iacute;rez<\/b> (Mar&iacute;sol para los cuates). Nacida en la Ciudad de M&eacute;xico. Edad, 49 a&ntilde;os. Lectora incansable desde los 4 a&ntilde;os de edad. Graduada como traductora en 1979, primer empleo fue en el diario derechista ya desaparecido <i>El Heraldo de M&eacute;xico<\/i>. Curso de posgrado en Traducci&oacute;n Literaria en El Colegio de M&eacute;xico (1980-82). Traductora empleada e independiente desde hace unos 30 a&ntilde;os(ingl&eacute;s, franc&eacute;s, espa&ntilde;ol). Tambi&eacute;n actriz de teatro (modestamente) durante unos 12 a&ntilde;os. Especializada en Traducci&oacute;n Jur&iacute;dica desde el a&ntilde;o 2000, diplomas de La Escuela Libre de Derecho. Durante los &uacute;ltimos 12 a&ntilde;os ha trabajado como asistente ejecutiva y traductora para importante despacho de abogados en la Ciudad de M&eacute;xico. Le fascinan la historia del mundo y de las religiones, y casi todos los temas incluso econom&iacute;a y medicina. &#8220;Activista de escritorio&#8221; desde el a&ntilde;o 2000. Cree que el amor y el humor son la mejor medicina, la experiencia, la curiosidad y el sentido com&uacute;n los mejores maestros.  <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><b>Photo Not Available<\/b><\/td>\n<td>\n<p><b>Tracy Dreyer<\/b> es traductor freelance basado en Am&eacute;rica Central. Su idioma nativo es ingl&eacute;s y es proficiente en espa&ntilde;ol, frances y portugu&eacute;s. Aparte de hacer traducciones para organizaciones gubernamentales y no-gubernamentales, universidades, y investigadores, ense&ntilde;a ingl&eacute;s en El Salvador, donde &eacute;l y su esposa tienen tres hijos. En su tiempo libre es voluntario de la iglesia Bah&aacute;&#8217;&iacute;. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/919.jpg\" width=\"67\" height=\"79\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Nalina Eggert<\/b> esta facinada con las palabras, entre otras cosas. Cuando no esta estudiando para su licenciatura en Estudios Latinoamericanos toca el sax, baila y prueba otros idiomas. Le encanta<br \/>\n  el desaf&iacute;o de una traducci&oacute;n del espa&ntilde;ol al ingl&eacute;s. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><b>Photo Not Available<\/b><\/td>\n<td>\n<p><b>Charlotte Elmitt<\/b> ha ense&ntilde;ado en la preparatoria en Inglaterra y vivido en Am&eacute;rica Central y M&eacute;xico haciendo trabajo voluntario. Tiene una maestr&iacute;a en Desarrollo Internacional, concentraci&oacute;n en las pandillas centroamericanas. Actualmente trabaja en una organizaci&oacute;n de investigaci&oacute;n de derechos humanos y en su tiempo libre trabaja como voluntaria. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/918.jpg\" width=\"68\" height=\"85\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Frances Lima Goodingham<\/b> naci&oacute; en Brasil, estudi&oacute; fotograf&iacute;a y sociolog&iacute;a<br \/>\n  en la <i>Pontif&iacute;cia Universidade Cat&oacute;lica do Rio de Janeiro<\/i> y se fue a vivir a Londres. Se gradu&oacute; en Antropolog&iacute;a Social del Goldsmiths College, University of London y hizo la maestr&iacute;a en Pol&iacute;tica Latinoamericana del Instituto de Estudios Latinoamericanos, ahora el Instituto para el Estudio de las Am&eacute;ricas de la Universidad de Londres. Actualmente trabaja como traductor calificada literaria y de las ciencias sociales. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/876.jpg\" width=\"60\" height=\"80\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Marina Muscan<\/b> es graduada del Colegio Nacional de la Defensa de Bucarest y de la Facultad de<br \/>\n  Comunicaci&oacute;n y Relaciones P&uacute;blica de la Escuela Nacional de Estudios Pol&iacute;ticos y Administraci&oacute;n P&uacute;blica. Adem&agrave;s tiene una maestr&iacute;a en Gesti&oacute;n de los Proyectos Internacionales y ahora esta siguiendo los cursos de maestria en Relaciones Internacionales en la Escuela Nacional de Estudios Pol&iacute;ticos y Administraci&oacute;n P&uacute;blica de Bucarest. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/920.jpg\" width=\"81\" height=\"77\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Adeola Oyelabi<\/b> estudia en Howard University, con una concentraci&oacute;n en Espa&ntilde;ol y otra en Ruso, y es de Rochester, Nueva York originalmente. Ella planea estudiar una maestr&iacute;a en Espa&ntilde;ol. Le gustar&iacute;a ser interprete de las Naciones Unidas y eventualmente ense&ntilde;ar espa&ntilde;ol en otros pa&iacute;ses. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/878.jpg\" width=\"60\" height=\"80\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Tony Phillips<\/b> es investigador y periodista sobre temas de comercio y finanzas internacionales con enfasis en dictadur&iacute;as y el OMC. Despu&eacute;s de dos d&eacute;cadas de la vida corporative en 20 paises, Tony construy&oacute; un coche en San Francisco y lo manej&oacute; a trav&eacute;s de 20 paises de Am&eacute;rica. Actualmente estudia la maestr&iacute;a sobre MERCOSUR en la Universidad de Buenos Aires. Su trabajo esta publicado en <a href=\"http:\/\/projectallende.org\/\">http:\/\/projectallende.org\/<\/a>. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><b>Photo Not Available<\/b><\/td>\n<td>\n<p><b>Annette Ramos<\/b> tiene una maestr&iacute;a en Espa&ntilde;ol y Literatura Latinoamericana y es una traductora freelance judicial. Actualmente le interesa lo que esta pasando en Am&eacute;rica Latina y el mundo hispanohablante y en ayudar a difundir puntos de vista alternatives lo m&aacute;s que se pueda. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/917.jpg\" width=\"65\" height=\"71\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Lorena Rodriguez Bojorquez-White<\/b> es originalmente de Guadalajara (Mexico), es Licenciada en Comercio Internacional por el ITESM y cuenta con una Maestr&iacute;a en Desarrollo Internacional del EHESS de Par&iacute;s (investigaci&oacute;n sobre el TLCAN y su impacto en la industria azucarera mexicana). Desde hace tres a&ntilde;os realiza evaluaciones de proyectos humanitarios para el Movimiento Internacional<br \/>\n  de la Cruz Roja en diferentes pa&iacute;ses del Caribe. Reside actualmente en la isla francesa de Guadeloupe. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/875.jpg\" width=\"50\" height=\"76\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Mar&iacute;a Roof<\/b> ense&ntilde;a Literatura y Cultura Latinoamericana en Howard University, en Washington, DC. Esta escribiendo un libro sobre poetas Chilenas no-reconocidas desde los principios del siglo veinte. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><b>Photo Not Available<\/b><\/td>\n<td>\n<p><b>Lezlie L. Shackell<\/b> es estudiante de postgrado en espa&ntilde;ol en &#8220;Howard University&#8221;. &nbsp;Durante los ocho a&ntilde;os que vivi&oacute; en el exterior, se radic&oacute; en el Ecuador durante cuatro a&ntilde;os donde desempe&ntilde;&oacute; funciones como coordinadora de eventos en la Embajada de los EE.UU. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/874.jpg\" width=\"60\" height=\"81\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Gracia Tenorio-Pearl<\/b> es Mexicana pero reside actualmente en Canada. Tiene la maestria en Relaciones<br \/>\n  Internacionales de Carleton University. Adem&aacute;s de espa&ntilde;ol habla ingl&eacute;s y franc&eacute;s. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/895.jpg\" width=\"75\" height=\"90\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Megan Tiano<\/b> esta en su &uacute;ltimo a&ntilde;o en Lehigh University en las carreras de Relaciones Internacionales y Espa&ntilde;ol con Estudios Latinoamericanos. Ella ha estudiado en Argentina en la Universidad de Buenos Aires y la Factultad Latino Americana de Ciencias Sociales (FLACSO). <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/877.jpg\" width=\"62\" height=\"80\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Sonja Wolf<\/b> hizo la carrera en Estudios Europeos Modernos en University College London y Maestr&iacute;a<br \/>\n  en Pol&iacute;tica Internacional de SOAS, University of London. Actualmente esta escribiendo su tesis doctoral sobre las repuestas a las pandillas de jovenes en El Salvador. Antes de comenzar su doctorado<br \/>\n  trabajaba en ONGs y las Naciones Unidas. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<p>&nbsp;<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"bottom\">\n<h2>Programa de las Am&eacute;ricas Analistas<\/h2>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/10\/37.jpg\" width=\"70\" height=\"101\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Eduardo Gudynas<\/b> es analista es CLAES D3E, un centro de investigaci&oacute;n y promoci&oacute;n del desarrollo sostenible (<a href=\"http:\/\/www.integracionsur.com\/\">www.integracionsur.com<\/a>). <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/irc\/921.jpg\" width=\"80\" height=\"80\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Talli Nauman<\/b> es una analista ambiental del Programa de las Am&eacute;ricas. Ella es fundadora y co-directora del proyecto internacional de medios de comunicaci&oacute;n independientes Periodismo para Elevar la Conciencia Ambiental, iniciado en 1994. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><img decoding=\"async\" src=\"\/images\/irc\/1115.jpg\" width=\"67.5\" height=\"88.5\" hspace=\"5\" vspace=\"5\"><\/td>\n<td>\n<p><b>Ariela Ruiz Caro<\/b> es economista por la Universidad Humboldt de Berl&iacute;n con maestr&iacute;a en procesos de integraci&oacute;n econ&oacute;mica por la Universidad de Buenos Aires. Es consultora internacional en temas de comercio, integraci&oacute;n y recursos naturales en la CEPAL y asesora de la Presidencia<br \/>\nde la Comisi&oacute;n de Representantes Permanentes del MERCOSUR. Ha sido funcionaria de la Comunidad Andina entre 1985 y 1994. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"middle\" align=\"center\"><b>Photo Not Available<\/b><\/td>\n<td>\n<p><b>Ra&uacute;l Zibechi<\/b> es analista internacional del semanario <i>Brecha<\/i> de Montevideo, docente e investigador sobre movimientos sociales en la Multiversidad Franciscana de Am&eacute;rica Latina, y asesor a varios grupos sociales. Es colaborador mensual con el Programa de las Am&eacute;ricas. <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<hr>\n<\/td>\n<\/tr>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Personal Tom Barry, Analista Senior y Fellow del Programa de las Am&eacute;ricas: Como analista senior, Tom Barry participa en asignar, escribir y redactar art&iacute;culos importantes y tambi&eacute;n definir objetivos estrat&eacute;gicos del Programa de las Am&eacute;ricas. Empez&oacute; su carrera como activista pol&iacute;tica y analista en Georgetown University en los 1960s. Trabaj&oacute; como periodista por el Navajo [&hellip;]<\/p>\n","protected":false},"author":48,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[],"tags":[],"coauthors":[],"class_list":["post-1862","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/posts\/1862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/comments?post=1862"}],"version-history":[{"count":0,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/posts\/1862\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/media?parent=1862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/categories?post=1862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/tags?post=1862"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/coauthors?post=1862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}