{"id":52010,"date":"2020-10-21T22:53:56","date_gmt":"2020-10-22T03:53:56","guid":{"rendered":"https:\/\/www.americas.org\/?p=52010\/"},"modified":"2020-11-03T14:14:50","modified_gmt":"2020-11-03T19:14:50","slug":"el-mas-vuelve-renovado-al-poder-en-bolivia","status":"publish","type":"post","link":"https:\/\/www.americas.org\/es\/el-mas-vuelve-renovado-al-poder-en-bolivia\/","title":{"rendered":"El MAS vuelve renovado al poder en Bolivia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-52011\" src=\"https:\/\/www.americas.org\/wp-content\/uploads\/2020\/10\/MAS-Victoria-e1603338787632.jpg\" alt=\"\" width=\"400\" height=\"266\" \/>Las elecciones del domingo 17 de octubre en Bolivia arrojaron resultados que no esperaba nadie: las especulaciones y las encuestas, indicaban que que el exministro de econom\u00eda de Evo Morales, Luis Arce, lograr\u00eda el primer puesto pero sin alcanzar una diferencia sufienciente como para vencer en primera vuelta. Sin embargo, el contundente 54% despej\u00f3 las dudas: el Movimiento al Socialismo (MAS) volver\u00e1 renovado al poder y lo har\u00e1 con mayor\u00edas parlamentarias.<\/p>\n<p>En segundo lugar, con el 29%, seg\u00fan datos oficiales reportados hasta ahora, qued\u00f3 un desdibujado Carlos Mesa quien declar\u00f3 unas horas despu\u00e9s de los primeros n\u00fameros: \u201cEl resultado del conteo r\u00e1pido es muy contundente y muy claro. Es un resultado que consideramos que no va a modificarse cuando conozcamos los resultados oficiales\u201d, afirm\u00f3 el dirigente de Comunidad Ciudadana. Algo similar, un par de horas antes, hab\u00eda hecho la presidenta de facto, Jeanine \u00c1\u00f1ez.<\/p>\n<p>En tercer puesto, con el 14% de los votos, qued\u00f3 el derechista Luis Fernando \u201cEl Macho\u201d Camacho, el ala m\u00e1s dura del golpe del a\u00f1o pasado y ex presidente del Comit\u00e9 C\u00edvico de Santa Cruz. La participaci\u00f3n en las elecciones fue del 88%, a\u00fan m\u00e1s alta que la de la elecci\u00f3n de 2005 en la que con el 53% de los votos Evo Morales gan\u00f3 por primera vez.<\/p>\n<p>El triunfo del binomio Luis Arce\u2013David Choquehuanca evidenci\u00f3, por un lado, una gran capacidad de renovaci\u00f3n dentro del campo popular. Por el otro, que ni con un golpe de estado el bloque conservador logr\u00f3 construir un espacio s\u00f3lido que fuera capaz de bloquear el retorno del MAS al poder. Los resultados muestran que no solo no hubo \u201cvoto \u00fatil\u201d antimasista, sino que ni unidos hubieran podido forzar una segunda vuelta.<\/p>\n<p><strong>Distribuci\u00f3n del voto<\/strong><\/p>\n<p>\u00c1\u00f1ez lleva casi un a\u00f1o en el poder y, hasta pocas semanas antes de las elecciones manifestaba su vocaci\u00f3n de ser una presidenta democr\u00e1tica. Sin embargo, tras la publicaci\u00f3n de una encuesta de mediados de septiembre que la posicionaba en cuarto lugar, decidi\u00f3 bajar su candidatura. Algo similar hizo poco despu\u00e9s el expresidente Jorge \u201cTuto\u201d Quiroga. La intenci\u00f3n de ambos era unificar al bloque conservador detr\u00e1s de una \u00fanica candidatura que pudiera evitar el retorno del MAS.<\/p>\n<p>Para ganar en Bolivia es necesario obtener m\u00e1s del 50% de los votos o m\u00e1s de 40 y 10 puntos de diferencia con el segundo. Mesa, un intelectual moderado sin partido pero con cierta base social en La Paz, perfilaba como el m\u00e1s id\u00f3neo para la tarea, dado que hab\u00eda tenido relativo \u00e9xito contra el oficialismo en las \u00faltimas elecciones. Aquella vez Morales gan\u00f3, pero la oposici\u00f3n denunci\u00f3 fraude. El autodenominado \u201cmovimiento de las pipitas\u201d cont\u00f3 con el apoyo de la OEA liderada por el uruguayo Luis Almagro, sectores medios movilizados en las grandes urbes, la polic\u00eda amotinada, unos militares que \u201csugierieron\u201d la renuncia del presidente y un activismo intenso y violento en el oriente del pa\u00eds.<\/p>\n<p>La nueva estrella que emergi\u00f3 de ese proceso fue Camacho, quien apareci\u00f3 en todos los canales del mundo entrando con una biblia gigante al Palacio Quemado mientras Evo Morales se veia forzado a partir al exilio.<\/p>\n<p>La hist\u00f3rica fractura regional en Bolivia vuelve ahora a ser una amenaza que sobrevolar\u00e1 la Bolivia que se viene. Camacho rechaz\u00f3 la idea de bajar su candidatura en pos de la unidad y en nombre de las elites de Santa Cruz de la Sierra que rechazaban la idea de volver a ceder poder a La Paz.<\/p>\n<p>Si Mesa es una figura que tras esta elecci\u00f3n pierde brillo, una lectura posible es que Camacho ahora haya consolidado un poder regional que, nuevamente, desde Oriente buscar\u00e1 irradiarse al resto del pa\u00eds. El 45% que obtuvo Camacho en Santa Cruz podr\u00eda ser un argumento que justifique la construcci\u00f3n de una oposici\u00f3n dura apoyada en una minor\u00eda intensa.\u00a0 Mesa, por su parte, venci\u00f3 en Tarija y en Beni.<\/p>\n<p><strong>El futuro gobierno<\/strong><\/p>\n<p>El MAS venci\u00f3 en Oruro, Pando, Potos\u00ed, Cochabamaba y se hizo muy fuerte en su basti\u00f3n, La Paz, donde obtuvo el 68 por ciento. A su vez, logr\u00f3 el segundo lugar con un considerable 35% en Santa Cruz. \u201cEl <em>voto \u00fatil<\/em> del mundo rural y urbano popular perif\u00e9rico fue, sin duda, a Arce, y eso defini\u00f3 su ventaja final\u201d, analiza Pablo Stefanoni.<\/p>\n<p>La solidez del triunfo del MAS abre interrogantes varios. Por un lado, el reto de administrar un pa\u00eds que atraviesa con particular crudeza el COVID-19 producto de un p\u00e9sima gesti\u00f3n de la administraci\u00f3n \u00c1\u00f1ez en t\u00e9rminos sanitarios y los impactos que la pandemia trajo a la econom\u00eda. En paralelo, deber\u00e1 lidiar con una econom\u00eda que ya no goza de la bonanza de los 14 a\u00f1os de gobierno de Morales, cuyos resultados eran conocidos como \u201cel milagro boliviano\u201d. Tal haza\u00f1a era, t\u00e9cnicamente, m\u00e9rito del ahora presidente Arce.<\/p>\n<p>Resta por ver cu\u00e1l ser\u00e1 el rol de Morales en el futuro. Todav\u00eda en el exilio en Buenos Aires, no se sabe cu\u00e1ndo, pero se da por descontado que volver\u00e1 al pa\u00eds. Hasta ahora fue el jefe de campa\u00f1a desde Argentina y para estas elecciones su candidatura como senador por Cochababa fue proscripta con el argumento de que, justamente, no estaba en Bolivia.<\/p>\n<p>El triunfo de Arce\u2013Choquehuanca mostr\u00f3 en el MAS una capacidad de renovaci\u00f3n que hace un a\u00f1o parec\u00eda impensable. De hecho, el futuro vicepresidente y ex canciller Choquehuanca, representante de los sectores aymaras del altiplano, tuvo roces con Morales en su momento por el debate en torno a la alternancia.<\/p>\n<p>Seg\u00fan Stefanoni, el MAS actu\u00f3 con una \u201cautonom\u00eda relativa\u201d mientras Evo Morales estaba exiliado en Buenos Aires y limitado en sus movimientos. As\u00ed, los legisladores fueron moderados respecto de los llamados a la resistencia que se o\u00edan desde Argentina. \u201cLo cierto es que no hab\u00eda un pedido masivo de que <em>Evo vuelva<\/em>; lo que exist\u00eda era m\u00e1s bien un rechazo a actos agraviantes del nuevo gobierno, como los conatos de quemas de wiphalas en las protestas anti-MAS y otros episodios considerados racistas, como las continuas referencias a las <em>hordas del MAS<\/em> y las columnas en la prensa sobre <em>el enemigo p\u00fablico n\u00famero uno<\/em> o el <em>c\u00e1ncer de Bolivia<\/em>\u201d, escribi\u00f3 el acad\u00e9mico.<\/p>\n<p>Un nuevo MAS asumir\u00e1 el poder hasta 2025 con mayor\u00edas en el Congreso. Los hechos mostraron una derecha ineficaz, que gestion\u00f3 mal y que no logr\u00f3 desplazarlo del poder de un modo sostenido. Con ciertos toques de heterodoxia, el partido logr\u00f3 una renovaci\u00f3n virtuosa.<\/p>\n<p>Pero no solo se ha renovado el MAS, la pregunta es si con Camacho surge un nuevo tipo de liderazgo duro y sin voluntad de negociaci\u00f3n. Esto agrietar\u00eda las hist\u00f3rica fracturas tanto \u00e9tnicas como regionales que, tras el golpe c\u00edvico prefectural de 2009 que sufri\u00f3 Morales, se sanaron con dinero: en los \u00faltimos a\u00f1os Morales ganaba en todo en todas las regiones con un acuerdo t\u00e1cito en el que las viejas elites ced\u00edan el poder pol\u00edtico a cambio de mantener su estructura de negocios en un pa\u00eds que crec\u00eda economicamente a ritmo sostenido.<\/p>\n<p>A partir de ahora, se abren nuevos interrogantes. La tarea de Arce-Choquehuanca ser\u00e1 la de crear un modelo propio capaz de conducir al conjunto de la sociedad boliviana. En este contexto, \u00bfc\u00f3mo ser\u00e1 la relaci\u00f3n del MAS gobernante con Evo Morales? \u00bfLograr\u00e1 Camacho -es decir, las elites cruce\u00f1as- constituirse como el l\u00edder detr\u00e1s del cual hegemonizar el \u201cantimasismo\u201d o el planteo seguir\u00e1 siendo el de una estricta expresi\u00f3n regional radicalizada? Estas preguntas encontrar\u00e1n una primera respuesta, seguramente pragm\u00e1tica, en el mapa de correlaciones de fuerzas que se dibuje en el pr\u00f3ximo Congreso.<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El triunfo del binomio Luis Arce\u2013David Choquehuanca evidenci\u00f3, por un lado, una gran capacidad de renovaci\u00f3n dentro del campo popular. Por el otro, que ni con un golpe de estado el bloque conservador logr\u00f3 construir un espacio s\u00f3lido que fuera capaz de bloquear el retorno del MAS al poder.<\/p>\n","protected":false},"author":473,"featured_media":52011,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[4884],"tags":[5650,7251,5651,7252,252],"coauthors":[7217],"class_list":["post-52010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-democracia","tag-bolivia","tag-bolivia-elecciones","tag-evo-morales","tag-luis-arce","tag-sudamerica"],"_links":{"self":[{"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/posts\/52010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/users\/473"}],"replies":[{"embeddable":true,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/comments?post=52010"}],"version-history":[{"count":3,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/posts\/52010\/revisions"}],"predecessor-version":[{"id":52014,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/posts\/52010\/revisions\/52014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/media\/52011"}],"wp:attachment":[{"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/media?parent=52010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/categories?post=52010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/tags?post=52010"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/coauthors?post=52010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}