{"id":727,"date":"2008-04-01T10:49:53","date_gmt":"2008-04-01T10:49:53","guid":{"rendered":"http:\/\/cipamericas.org\/?p=727"},"modified":"2008-05-23T14:21:29","modified_gmt":"2008-05-23T14:21:29","slug":"5116","status":"publish","type":"post","link":"https:\/\/www.americas.org\/es\/5116\/","title":{"rendered":"La verdadera crisis del campo argentino"},"content":{"rendered":"<p><strong>El 11 de marzo del corriente el gobierno argentino estableci&oacute; un incremento de las retenciones sobre las exportaciones de soja, elevando el canon del 33<\/strong><strong>% <\/strong><strong> al 44% y aplicando un sistema de retenciones m&oacute;viles que var&iacute;a de acuerdo al precio internacional de la soja. La respuesta por parte de los productores sojeros no dej&oacute; de esperarse. <\/strong><\/p>\n<p>El objetivo declarado del incremento en las retenciones fue el de dar un paso en los intentos del gobierno en la redistribuci&oacute;n de la riqueza al mismo tiempo que intentar frenar el avance del monocultivo de soja apoyando con esos fondos otras producciones. <\/p>\n<p>Pocos d&iacute;as despu&eacute;s cuatro entidades del agro (Confederaciones Rurales Argentinas, Sociedad Rural Argentina, Confederaci&oacute;n de Asociaciones Rurales de Buenos Aires y La Pampa y la Federaci&oacute;n Agraria Argentina) que agrupan a distintos sectores de los productores sojeros (desde los grandes terratenientes a los medianos y peque&ntilde;os productores) lanzaron en conjunto un <em>lock-out<\/em> agrario, cortando las principales rutas de transporte de alimentos y provocando un grave problema por el desabastecimiento de alimentos. El &uacute;nico reclamo de estas protestas es el de la eliminaci&oacute;n de esta medida. <\/p>\n<p>Junto a ellos, los poderosos medios de comunicaci&oacute;n ligados a estos intereses empresariales inundaron los noticieros hablando de un &quot;paro hist&oacute;rico&quot; y de la vuelta de los &quot;cacerolazos&quot;. Muy lejos est&aacute;n estos cacerolazos de aquellos que se hicieron o&iacute;r en todo el mundo en diciembre del 2001. <\/p>\n<p>A pesar de la invitaci&oacute;n al di&aacute;logo de la presidenta, las organizaciones rurales han decidido continuar con la medida de fuerza creando un panorama de incertidumbre e inestabilidad ins&oacute;lito por ser producido por el sector que m&aacute;s se enriqueci&oacute; en los &uacute;ltimos a&ntilde;os con la situaci&oacute;n creada en Argentina a partir de la devaluaci&oacute;n del a&ntilde;o 2002. <\/p>\n<p>Muy lejos de ellas las organizaciones campesinas apoyan las retenciones pero exigen una profundizaci&oacute;n de las medidas que reviertan el modelo de &quot;republiqueta sojera&quot; instalado en la Argentina a partir de la d&eacute;cada de los 90. <\/p>\n<p>Frente a la actual crisis provocada por el cierre patronal de los productores rurales de soja, vale la pena detenerse a mirar un poco m&aacute;s all&aacute; de la actual coyuntura para entender de qu&eacute; se trata y poder dar una mirada que no oculte detr&aacute;s de un &aacute;rbol el bosque de problemas que nuestra sociedad enfrenta. Sin embargo parece que el avance de la frontera agr&iacute;cola durante las &uacute;ltimas d&eacute;cadas nos ha dejado no solamente sin bosques reales sino tambi&eacute;n sin la capacidad de ver los bosques de ideas que se ocultan detr&aacute;s de esta situaci&oacute;n emergente. <\/p>\n<p>Sin duda el debate sobre la necesaria distribuci&oacute;n de la renta agraria o la manera de aplicar las retenciones a grandes y peque&ntilde;os productores es parte de un proceso necesario y adeudado por la sociedad argentina. <\/p>\n<p>Pero de ninguna manera podemos dejar de analizar como hemos llegado a esta situaci&oacute;n, cu&aacute;les son los verdaderos problemas que enfrentamos y sobre todo, cu&aacute;les son las consecuencias de un modelo que ha invadido la Argentina en tan s&oacute;lo 12 a&ntilde;os. Este modelo produce ganancias espectaculares para algunos y problemas grav&iacute;simos para toda una sociedad que a&uacute;n no reacciona, aturdida por los cantos de sirena de las &quot;producciones record&quot;. <\/p>\n<h3>El avance de la soja<\/h3>\n<p>Fue a mediados de la d&eacute;cada del 90 cuando el gobierno menemista, de la mano del entonces Secretario de Agricultura Felipe Sol&aacute;, autoriz&oacute; el cultivo de la soja transg&eacute;nica en Argentina. A partir de all&iacute;, en un crecimiento nunca antes registrado en la historia de la agricultura mundial, la soja transg&eacute;nica comenz&oacute; a invadir nuestra tierra para llegar a ocupar hoy m&aacute;s del 50% de la superficie agr&iacute;cola. <\/p>\n<p>La imposici&oacute;n de este modelo sin ning&uacute;n tipo de regulaci&oacute;n gubernamental abri&oacute; las puertas para lo que acertadamente algunos investigadores dieron en llamar &quot;una maquinaria de hambre, deforestaci&oacute;n y devastaci&oacute;n socioecol&oacute;gica&quot;<a href=\"#_ftn1\" name=\"_ftnref1\">1<\/a> en la que la destrucci&oacute;n de h&aacute;bitat, la p&eacute;rdida de bosque nativo, la invasi&oacute;n de transg&eacute;nicos, el monocultivo, la contaminaci&oacute;n ambiental, el desplazamiento de producciones regionales, la concentraci&oacute;n de la tierra y el desplazamiento de la poblaci&oacute;n rural formaron un combo explosivo del que todos los argentinos pagaremos las consecuencias. <\/p>\n<p>Abordemos solamente uno de los impactos de este modelo: la situaci&oacute;n de los suelos. Es absolutamente imprescindible tomar conciencia de que con las exportaciones de soja lo que estamos haciendo es vender uno de los m&aacute;s ricos de los recursos naturales que poseemos los argentinos que es nuestro suelo. La brutal extracci&oacute;n de nutrientes que se realiza en las 17 millones de hect&aacute;reas de soja que parten hacia China o la Uni&oacute;n Europea para engordar su ganado va desangrando nuestro territorio, dejando tierra rasa para las futuras generaciones. <\/p>\n<p>No en vano el gobierno nacional anunci&oacute; junto al aumento de las retenciones un plan de apoyo para la fertilizaci&oacute;n agr&iacute;cola. Lo que el gobierno no comprende es que no hay ning&uacute;n tipo de fertilizaci&oacute;n a gran escala que pueda devolver la vida a un suelo que ha sido esquilmado de la manera en que se lo est&aacute; haciendo. <\/p>\n<p>Pero por otra parte este suelo no es &quot;propiedad&quot; de los propietarios de la tierra, sino que, como recurso natural y tal como lo plantea la Constituci&oacute;n Argentina en su reforma de 1994, es un patrimonio de todos los argentinos. Vale la pena recordar su art&iacute;culo 41: &quot;Todos los habitantes gozan del derecho a un ambiente sano, equilibrado, apto para el desarrollo humano y para que las actividades productivas satisfagan las necesidades presentes sin comprometer las de las generaciones futuras, y tienen el deber de preservarlo &#8230; Las autoridades proveer&aacute;n a la protecci&oacute;n de este derecho, a la utilizaci&oacute;n racional de los recursos naturales, a la preservaci&oacute;n del patrimonio natural y cultural y de la diversidad biol&oacute;gica, y a la informaci&oacute;n y educaci&oacute;n ambientales&quot;. <\/p>\n<p>Por otro lado la misma Constituci&oacute;n plantea en su art&iacute;culo 17 el reconocimiento de &quot;la preexistencia &eacute;tnica y cultural de los pueblos ind&iacute;genas argentinos&quot; y all&iacute; se compromete a &quot;Garantizar el respeto a su identidad &#8230; y Asegurar su participaci&oacute;n en la gesti&oacute;n referida a sus recursos naturales y a los dem&aacute;s intereses que los afecten&quot;. <\/p>\n<p>Ninguna de estas obligaciones ha sido cumplida hasta ahora por el Estado Argentino y esta es una de las principales deudas internas tanto con el total de la sociedad como con los pueblos ind&iacute;genas. Tampoco ninguna de las entidades rurales que hoy protestan ha hecho absolutamente nada en resguardo de estos bienes comunes. Todo lo contrario: cada productor ha avanzado hasta donde pudo (incluyendo banquinas) con el desierto verde de la soja. <\/p>\n<h3>Los verdaderos ganadores<\/h3>\n<p>Por supuesto que los &quot;padres&quot; del modelo, las grandes corporaciones agroalimentarias (Monsanto, Syngenta, Cargill) permanecen silenciosas y no emiten ninguna declaraci&oacute;n ni opini&oacute;n ni est&aacute;n presentes en los cortes de ruta. <\/p>\n<p>Sin embargo ellas han sido las que, como acaba de definir Ra&uacute;l Montengro<a href=\"#_ftn2\" name=\"_ftnref2\">2<\/a>, nos han hecho &quot;rehenes de Monsanto&quot; con la invasi&oacute;n de soja transg&eacute;nica que hoy representa el 99% de los cultivos de soja en Argentina. Mientras los sojeros argentinos cortaban las rutas, Monsanto anunciaba el d&iacute;a martes 25 en Nueva York el aumento de su pron&oacute;stico de ganancias para el 2008 &quot;citando la fuerte demanda de ma&iacute;z y semillas de soja y la mayor demanda de herbicidas&quot;<a href=\"#_ftn3\" name=\"_ftnref3\">3<\/a> y a principios del 2008 informaba que hab&iacute;a triplicado sus ganancias con respecto al mismo trimestre del a&ntilde;o anterior<a href=\"#_ftn4\" name=\"_ftnref4\">4<\/a>. <\/p>\n<p>Evidentemente no se muestran muy preocupados por las retenciones en Argentina. <\/p>\n<p>Tampoco Cargill, Dreyfus, ADM o Bunge son parte de la protesta, aunque como bien lo se&ntilde;ala el Grupo de Reflexi&oacute;n Rural<a href=\"#_ftn5\" name=\"_ftnref5\">5<\/a> ellos son los verdaderos exportadores y quienes deber&iacute;an estar asumiendo el costo de las retenciones. <\/p>\n<p>Ni siquiera son de la partida algunos de los grandes pooles de siembra, como el grupo Grobo de Gustavo Grobocopatel que no pertenece a ninguna de las entidades que convocan a la protesta y que representan la mayor parte del cultivo de soja en Argentina, pero a los que seguramente poco les afecta un 10% m&aacute;s o menos de retenciones. <\/p>\n<h3>Soberan&iacute;a Alimentaria<\/h3>\n<p>Las organizaciones campesinas e ind&iacute;genas han expresado claramente su rechazo a este modelo desde hace m&aacute;s de una d&eacute;cada. Ya en la &quot;Marcha por la defensa de nuestros derechos, Contra la precarizaci&oacute;n de la vida, el saqueo de los bienes naturales y la contaminaci&oacute;n&quot; realizada el 24 de septiembre del 2007 hablaban de &quot;Un saqueo paulatino que en algunos a&ntilde;os nos dejar&aacute; sin las riquezas de la naturaleza. Riqueza que para ellos son recursos. Pero para nosotros son los bienes naturales y culturales de nuestros pueblos.&quot;<a href=\"#_ftn6\" name=\"_ftnref6\">6<\/a><\/p>\n<p>Ahora, el Movimiento Nacional Campesino Ind&iacute;gena (MNCI), integrado por 15,000 familias de siete provincias, con absoluta claridad plantea que &quot;esta es una oportunidad para redefinir las estrategias de desarrollo en funci&oacute;n de la agricultura campesina ind&iacute;gena, el peque&ntilde;o agricultor que vive en su predio, el trabajador rural. Esa estrategia debe contar como actores fundamentales a las organizaciones campesinas y los pueblos originarios, destinar recursos a cr&eacute;ditos y subsidios que mejoren la infraestructura comunitaria, productiva y de servicios sociales en el campo profundo, detener los desalojos de familias campesinas e ind&iacute;genas, planificar la redistribuci&oacute;n de la tierra y el repoblamiento del campo, garantizar la producci&oacute;n de alimentos sanos para la poblaci&oacute;n y centralizar en el Gobierno las exportaciones para regular los precios internos y redistribuir los ingresos.&quot;<a href=\"#_ftn7\" name=\"_ftnref7\">7<\/a><\/p>\n<p>Es hora de que escuchemos a quienes siempre han alimentado a nuestro pueblo y lo seguir&aacute;n haciendo en el futuro a pesar del agronegocio y los discursos rimbombantes de la gente &quot;del campo&quot;. Es hora de que aprendamos a ver el bosque y cuidarlo. <\/p>\n<h3>Notas<\/h3>\n<ol>\n<li><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a>La soja transg&eacute;nica en Am&eacute;rica Latina: una maquinaria de hambre, deforestaci&oacute;n y devastaci&oacute;n socioecol&oacute;gica, <a href=\"http:\/\/www.biodiversidadla.org\/content\/view\/full\/23297\">http:\/\/www.biodiversidadla.org\/content\/view\/full\/23297<\/a> <\/li>\n<li><a href=\"#_ftnref2\" name=\"_ftn2\"><\/a>Argentina: rehenes de Monsanto, <a href=\"http:\/\/www.biodiversidadla.org\/content\/view\/full\/39814\">http:\/\/www.biodiversidadla.org\/content\/view\/full\/39814<\/a> <\/li>\n<li><a href=\"#_ftnref3\" name=\"_ftn3\"><\/a>Monsanto eleva meta de ganancias de a&ntilde;o fiscal 2008, <a href=\"http:\/\/lta.reuters.com\/article\/businessNews\/idLTAN2538056820080325\">http:\/\/lta.reuters.com\/article\/businessNews\/idLTAN253805682008032<\/a> <\/li>\n<li><a href=\"#_ftnref4\" name=\"_ftn4\"><\/a>Triplica Monsanto ganancias en negocio de venta de semillas transg&eacute;nicas, <a href=\"http:\/\/www.planetaazul.com.mx\/www\/2008\/01\/07\/triplica-monsanto-ganancias-en-negocio-de-venta-de-semillas-transgenicas\/\">http:\/\/www.planetaazul.com.mx\/www\/2008\/01\/07\/triplica-monsanto-ganancias-en-negocio-de-venta-de-semillas-transgenicas\/<\/a> <\/li>\n<li><a href=\"#_ftnref5\" name=\"_ftn5\"><\/a>El GRR frente al paro agrario, <a href=\"http:\/\/www.grr.org.ar\/\">http:\/\/www.grr.org.ar\/<\/a><\/li>\n<li><a href=\"#_ftnref6\" name=\"_ftn6\"><\/a>Argentina: marcha por la defensa de nuestros derechos. Contra la precarizaci&oacute;n de la vida, el saqueo de los bienes naturales y la contaminaci&oacute;n, <a href=\"http:\/\/www.biodiversidadla.org\/content\/view\/full\/35016\">http:\/\/www.biodiversidadla.org\/content\/view\/full\/3501<\/a><\/li>\n<li><a href=\"#_ftnref7\" name=\"_ftn7\"><\/a>Argentina: no al modelo de agronegocios actual. Exigimos pol&iacute;ticas para los campesinos ind&iacute;genas, <a href=\"http:\/\/www.biodiversidadla.org\/content\/view\/full\/39802\">http:\/\/www.biodiversidadla.org\/content\/view\/full\/39802<\/a> <\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 11 de marzo del corriente el gobierno argentino estableci&oacute; un incremento de las retenciones sobre las exportaciones de soja, elevando el canon del 33% al 44% y aplicando un sistema de retenciones m&oacute;viles que var&iacute;a de acuerdo al precio internacional de la soja. La respuesta por parte de los productores sojeros no dej&oacute; de [&hellip;]<\/p>\n","protected":false},"author":232,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[],"tags":[],"coauthors":[],"class_list":["post-727","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/posts\/727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/users\/232"}],"replies":[{"embeddable":true,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/comments?post=727"}],"version-history":[{"count":0,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/posts\/727\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/media?parent=727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/categories?post=727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/tags?post=727"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.americas.org\/es\/wp-json\/wp\/v2\/coauthors?post=727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}